{"id":168,"count":2,"description":"","link":"https:\/\/www.bartlett.com\/blog\/tag\/tree-safety-2\/","name":"tree safety","slug":"tree-safety-2","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>tree safety Archives - Tree Topics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bartlett.com\/blog\/tag\/tree-safety-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tree safety Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bartlett.com\/blog\/tag\/tree-safety-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Tree Topics\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BartlettTreeExp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/tag\\\/tree-safety-2\\\/\",\"url\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/tag\\\/tree-safety-2\\\/\",\"name\":\"tree safety Archives - Tree Topics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/tag\\\/tree-safety-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/tag\\\/tree-safety-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"tree safety\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/\",\"name\":\"Tree Topics\",\"description\":\"The Bartlett Tree Experts Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/#organization\",\"name\":\"Bartlett Tree Experts Tree Topics\",\"url\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cropped-bartlett-blog-logo-new.png\",\"contentUrl\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cropped-bartlett-blog-logo-new.png\",\"width\":153,\"height\":66,\"caption\":\"Bartlett Tree Experts Tree Topics\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bartlett.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bartletttreeexperts\\\/\",\"https:\\\/\\\/x.com\\\/BartlettTreeExp\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"tree safety Archives - Tree Topics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bartlett.com\/blog\/tag\/tree-safety-2\/","og_locale":"en_US","og_type":"article","og_title":"tree safety Archives","og_url":"https:\/\/www.bartlett.com\/blog\/tag\/tree-safety-2\/","og_site_name":"Tree Topics","twitter_card":"summary_large_image","twitter_site":"@BartlettTreeExp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.bartlett.com\/blog\/tag\/tree-safety-2\/","url":"https:\/\/www.bartlett.com\/blog\/tag\/tree-safety-2\/","name":"tree safety Archives - Tree Topics","isPartOf":{"@id":"https:\/\/www.bartlett.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.bartlett.com\/blog\/tag\/tree-safety-2\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bartlett.com\/blog\/tag\/tree-safety-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bartlett.com\/blog\/"},{"@type":"ListItem","position":2,"name":"tree safety"}]},{"@type":"WebSite","@id":"https:\/\/www.bartlett.com\/blog\/#website","url":"https:\/\/www.bartlett.com\/blog\/","name":"Tree Topics","description":"The Bartlett Tree Experts Blog","publisher":{"@id":"https:\/\/www.bartlett.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bartlett.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.bartlett.com\/blog\/#organization","name":"Bartlett Tree Experts Tree Topics","url":"https:\/\/www.bartlett.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bartlett.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.bartlett.com\/blog\/wp-content\/uploads\/2024\/10\/cropped-bartlett-blog-logo-new.png","contentUrl":"https:\/\/www.bartlett.com\/blog\/wp-content\/uploads\/2024\/10\/cropped-bartlett-blog-logo-new.png","width":153,"height":66,"caption":"Bartlett Tree Experts Tree Topics"},"image":{"@id":"https:\/\/www.bartlett.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bartletttreeexperts\/","https:\/\/x.com\/BartlettTreeExp"]}]}},"_links":{"self":[{"href":"https:\/\/www.bartlett.com\/blog\/wp-json\/wp\/v2\/tags\/168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bartlett.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.bartlett.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.bartlett.com\/blog\/wp-json\/wp\/v2\/posts?tags=168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}